{"id":244,"date":"2014-05-05T00:44:18","date_gmt":"2014-05-05T00:44:18","guid":{"rendered":"https:\/\/diocesanos.es\/blogs\/equipotic\/?p=244"},"modified":"2014-05-05T00:44:18","modified_gmt":"2014-05-05T00:44:18","slug":"cientos-de-videos-educativos-clasificados-por-nivel-y-por-materia","status":"publish","type":"post","link":"https:\/\/diocesanos.es\/blogs\/equipotic\/2014\/05\/05\/cientos-de-videos-educativos-clasificados-por-nivel-y-por-materia\/","title":{"rendered":"Cientos de v\u00eddeos educativos clasificados por nivel y por materia"},"content":{"rendered":"<h1><a title=\"schoolsworld\" href=\"http:\/\/www.schoolsworld.tv\/\" target=\"_blank\">SchoolsWorld.tv<\/a><\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-content\/uploads\/sites\/2\/2014\/05\/schoolsworldtv.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-245\" src=\"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-content\/uploads\/sites\/2\/2014\/05\/schoolsworldtv.jpeg\" alt=\"schoolsworldtv\" width=\"263\" height=\"192\" \/><\/a><\/p>\n<p>es un portal de v\u00eddeos especializado en el mundo educativo. All\u00ed podemos encontrar cientos de v\u00eddeos para estudiantes, desde minidocumentales a experiencias cient\u00edficas, pasando por demostraciones y explicaciones de profesores.<\/p>\n<p>Los v\u00eddeos est\u00e1n clasificados y permiten incluirse en cualquier otra p\u00e1gina web para que los estudiantes los incrusten en sus blogs acad\u00e9micos. Adem\u00e1s de v\u00eddeos tambi\u00e9n podemos encontrar documentos, presentaciones y juegos, siempre relacionados con los v\u00eddeos disponibles.<\/p>\n<p>Aunque el contenido se encuentra en ingl\u00e9s, es una buena base de datos de contenido que los profesores pueden usar para mostrar en clase, traduciendo lo que sea necesario o explicando lo que va apareciendo en pantalla.<\/p>\n<h1><a title=\"educatina\" href=\"http:\/\/www.educatina.com\/\" target=\"_blank\">educatina.com<\/a><\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-content\/uploads\/sites\/2\/2014\/05\/educatina.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-246\" src=\"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-content\/uploads\/sites\/2\/2014\/05\/educatina.jpeg\" alt=\"educatina\" width=\"240\" height=\"117\" \/><\/a><\/p>\n<p>Esta web que ofrece la posibilidad de consultar de forma gratuita m\u00e1s de 3.000 v\u00eddeos de las m\u00e1s diversas materias <strong>en nuestro idioma<\/strong>.<\/p>\n<h1>youtube<\/h1>\n<p>Por supuesto, siempre tenemos youtube, aunque el trabajo de investigaci\u00f3n en dicho portal puede ser demasiado agotador.<\/p>\n<ul>\n<li><a title=\"f\u00edsica\" href=\"http:\/\/wwwhatsnew.com\/2013\/08\/11\/6-canales-youtube-explicaciones-faciles-fisica\/\" target=\"_blank\">explicaciones de f\u00edsica<\/a><\/li>\n<li><a title=\"matem\u00e1ticas\" href=\"http:\/\/wwwhatsnew.com\/2013\/04\/15\/6-sitios-y-canales-con-explicaciones-de-matematicas-mas-que-faciles\/\" target=\"_blank\">de matem\u00e1ticas<\/a><\/li>\n<li><a href=\"http:\/\/wwwhatsnew.com\/2012\/12\/08\/videos-de-quimica-en-espanol\/\" target=\"_blank\">de qu\u00edmica<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SchoolsWorld.tv es un portal de v\u00eddeos especializado en el mundo educativo. All\u00ed podemos encontrar cientos de v\u00eddeos para estudiantes, desde minidocumentales a experiencias cient\u00edficas, pasando por demostraciones y explicaciones de profesores. Los v\u00eddeos est\u00e1n clasificados y permiten incluirse en cualquier otra p\u00e1gina web para que los estudiantes los incrusten en sus blogs acad\u00e9micos. Adem\u00e1s de &hellip; <a href=\"https:\/\/diocesanos.es\/blogs\/equipotic\/2014\/05\/05\/cientos-de-videos-educativos-clasificados-por-nivel-y-por-materia\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Cientos de v\u00eddeos educativos clasificados por nivel y por materia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,40],"tags":[17,10],"class_list":["post-244","post","type-post","status-publish","format-standard","hentry","category-documentacion","category-formacion-2","tag-formacion","tag-video"],"_links":{"self":[{"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/posts\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/comments?post=244"}],"version-history":[{"count":0,"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/posts\/244\/revisions"}],"wp:attachment":[{"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/media?parent=244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/categories?post=244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocesanos.es\/blogs\/equipotic\/wp-json\/wp\/v2\/tags?post=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}